{"id":770,"date":"2015-08-13T13:17:19","date_gmt":"2015-08-13T13:17:19","guid":{"rendered":"http:\/\/www.pamina-business.com\/?p=770"},"modified":"2015-07-28T09:24:02","modified_gmt":"2015-07-28T09:24:02","slug":"technologieregion-karlsruhe-stellt-ihr-mobilitatsportal-vor","status":"publish","type":"post","link":"https:\/\/www.pamina-business.com\/de\/technologieregion-karlsruhe-stellt-ihr-mobilitatsportal-vor\/","title":{"rendered":"TechnologieRegion Karlsruhe stellt ihr Mobilit\u00e4tsportal vor"},"content":{"rendered":"<p><strong>\u00a0<\/strong><\/p>\n<p>Wo rollt, klemmt, steht der Verkehr? Wie sehen meine M\u00f6glichkeiten zum Parken oder Umsteigen aus, welche Baustellen und Geschwindigkeitsbegrenzungen erwarten mich? All diese und weitere Fragen kann das Mobilit\u00e4tsportal der TechnologieRegion Karlsruhe (TRK) Pendlern und heutigen sowie potenziellen k\u00fcnftigen B\u00fcrgerinnen und B\u00fcrgern auf <a href=\"http:\/\/mobilitaet.trk.de\/index.html\" target=\"_self\">www.mobilitaet.trk.de<\/a> beantworten &#8211; \u00fcberwiegend in Echtzeit.<\/p>\n<p>Der Verkehrsfluss wird im Drei-Minuten-Takt transportiert, Webcams zeigen live etwa die Situation auf der Rheinbr\u00fccke, die neben der F\u00e4cherstadt bislang f\u00fcnf beteiligten St\u00e4dte &#8211; Baden-Baden, Ettlingen, Rastatt, Rheinstetten und Stutensee &#8211; lokale Details.<\/p>\n<p>Der TRK-Vorsitzende, Karlsruhes Oberb\u00fcrgermeister Dr. Frank Mentrup, sowie Wilfried Schreiber vom Tiefbauamt und Michael Danzeglocke, Gesch\u00e4ftsf\u00fchrer des Kommunikationsb\u00fcros pandesign, haben diese umfassende Erweiterung des Karlsruher Info-Portals (vmz.karlsruhe.de) am Montag, 13. Juli, im Rathaus am Marktplatz pr\u00e4sentiert. Die offiziell um 10 Uhr gestartete Informationsplattform b\u00fcndelt alle Angaben zu Kraftfahrzeug- und Radverkehr, zum \u00d6PNV, zur multimodalen Mobilit\u00e4t: gespeist unter anderem durch die L\u00e4nder Baden-W\u00fcrttemberg, Rheinland-Pfalz und Frankreich sowie den Karlsruher Verkehrsverbund und Car-Sharing-Anbieter.<\/p>\n<p><strong>Passend zum Verkaufsoffenen Sonntag<\/strong><br \/>\n\u201eWir k\u00f6nnen einen wohl einzigartigen, l\u00e4nder- und nationen\u00fcbergreifenden Service anbieten\u201c, sprach Mentrup von einem \u201eganz starken Signal, dass die TechnologieRegion Karlsruhe und auch die Zusammenarbeit von Wirtschaft, Wissenschaft und Verwaltung keine abstrakten Begriffe sind. Ich freue mich, dass wir das Portal gerade jetzt in der Woche vor dem Verkaufsoffenen Sonntag freigeben konnten. Hier kann man sich am Sonntagmittag anschauen, wie die Stra\u00dfenlage ist, wie die Parkh\u00e4user belegt sind, entspannter planen und einkaufen.\u201c Tats\u00e4chlich zeigt eine Symbolleiste beispielsweise auf, welche Baustellen gerade wo, wie lange und warum zu ber\u00fccksichtigen sind &#8211; und auch eine Baustellenvorschau ist Teil des kostenlos nutzbaren Produkts. Der Zugang erfolgt \u00fcber die Webauftritte der TRK und aller beteiligten Kommunen.<\/p>\n<p>Parkautomaten- sowie Parkscheinzonen und jene f\u00fcr Bewohnerparken, F\u00e4hrverbindungen mit Link zu den Fahrpl\u00e4nen, Fahrradleihangebote, Parken und Mitfahren, station\u00e4re und potenzielle mobile Geschwindigkeitsmessungen mit Beweggrund, etwa der N\u00e4he zu einem Kindergarten: abrufbar auf einer mit durchg\u00e4ngig einheitlicher Karten- und Informations\u00fcbersicht gestalteten, vielschichtigen Oberfl\u00e4che. Das gilt angepasst ebenso f\u00fcr Tablets und andere mobile Endger\u00e4te. Zwei Kernkompetenzfelder der TRK &#8211; IT und Mobilit\u00e4t &#8211; spiegeln sich nach jahrelanger Entwicklungsarbeit unter Federf\u00fchrung des Karlsruher Tiefbauamts auch in Struktur und Auspr\u00e4gung des Portals wider, das gr\u00f6\u00dftenteils von regionalen Firmen realisiert wurde.<\/p>\n<p><strong>Zuk\u00fcnftig noch mobiler und flexibler<\/strong><br \/>\nNur Wochen nach Inbetriebnahme des st\u00e4dtischen Portals im Mai 2010 kam der Gedanke einer Ausdehnung auf, der nun Realit\u00e4t ist. Das als erfolgreichstes Kooperationsprojekt beim deutschen E-Governementpreis 2014 ausgezeichnete Konzept bietet zudem Potenzial zur erweiterten Darstellung der Vernetzung: etwa im Zusammenhang mit dem TRK-Projekt RegioMove. K\u00fcnftig, blickte Mentrup auf die n\u00e4chste Entwicklungsstufe voraus, soll das Endger\u00e4t dem Nutzer automatisch Vorschl\u00e4ge zur optimalen Route und zum sonstigen Verkehrsverhalten unterbreiten.<\/p>\n<p>Die App KA-Mobil bildet schon heute auch die Region ab und soll schlie\u00dflich &#8211; wenn weitere Akteure mit an Bord sind, um als ebenso aktuelles und umfassendes \u00c4quivalent zum Webportal zu funktionieren -, in TRK-Mobil m\u00fcnden. Mindestens Bruchsal, Germersheim und W\u00f6rth sind bereits stark an einer Teilnahme interessiert. Datendichte, Transparenz und Aussagekraft sollen immer noch weiter zunehmen.<\/p>\n<p><em>Quelle<\/em> : Verkehr-Newsletter der IHK Karsruhe vom 17.07.2015<\/p>\n<p><em>Kontak<\/em>t : <a href=\"&#x6d;&#x61;&#105;&#108;t&#x6f;&#x3a;&#x69;&#110;&#102;o&#x40;&#x6b;&#x61;&#114;&#108;s&#x72;&#x75;&#x68;&#101;&#46;i&#x68;&#x6b;&#x2e;&#100;e\" target=\"_blank\">&#105;n&#x66;o&#x40;k&#x61;r&#x6c;&#115;&#x72;&#117;&#x68;&#101;&#x2e;&#105;h&#107;&#46;&#x64;e<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Wo rollt, klemmt, steht der Verkehr? Wie sehen meine M\u00f6glichkeiten zum Parken oder Umsteigen aus, welche Baustellen und Geschwindigkeitsbegrenzungen erwarten mich? All diese und weitere Fragen kann das Mobilit\u00e4tsportal der TechnologieRegion Karlsruhe (TRK) Pendlern und heutigen sowie potenziellen k\u00fcnftigen B\u00fcrgerinnen und B\u00fcrgern auf www.mobilitaet.trk.de beantworten &#8211; \u00fcberwiegend in Echtzeit. Der Verkehrsfluss wird im Drei-Minuten-Takt [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[62],"tags":[],"class_list":["post-770","post","type-post","status-publish","format-standard","hentry","category-mobilitat-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TechnologieRegion Karlsruhe stellt ihr Mobilit\u00e4tsportal vor - PAMINA Business Club<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.pamina-business.com\/de\/technologieregion-karlsruhe-stellt-ihr-mobilitatsportal-vor\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TechnologieRegion Karlsruhe stellt ihr Mobilit\u00e4tsportal vor - PAMINA Business Club\" \/>\n<meta property=\"og:description\" content=\"\u00a0 Wo rollt, klemmt, steht der Verkehr? Wie sehen meine M\u00f6glichkeiten zum Parken oder Umsteigen aus, welche Baustellen und Geschwindigkeitsbegrenzungen erwarten mich? All diese und weitere Fragen kann das Mobilit\u00e4tsportal der TechnologieRegion Karlsruhe (TRK) Pendlern und heutigen sowie potenziellen k\u00fcnftigen B\u00fcrgerinnen und B\u00fcrgern auf www.mobilitaet.trk.de beantworten &#8211; \u00fcberwiegend in Echtzeit. Der Verkehrsfluss wird im Drei-Minuten-Takt [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.pamina-business.com\/de\/technologieregion-karlsruhe-stellt-ihr-mobilitatsportal-vor\/\" \/>\n<meta property=\"og:site_name\" content=\"PAMINA Business Club\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-13T13:17:19+00:00\" \/>\n<meta name=\"author\" content=\"Monique STUTZMANN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Monique STUTZMANN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/technologieregion-karlsruhe-stellt-ihr-mobilitatsportal-vor\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/technologieregion-karlsruhe-stellt-ihr-mobilitatsportal-vor\\\/\"},\"author\":{\"name\":\"Monique STUTZMANN\",\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/#\\\/schema\\\/person\\\/9ab02536dbdbc5e3ef40bbc3452c8c69\"},\"headline\":\"TechnologieRegion Karlsruhe stellt ihr Mobilit\u00e4tsportal vor\",\"datePublished\":\"2015-08-13T13:17:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/technologieregion-karlsruhe-stellt-ihr-mobilitatsportal-vor\\\/\"},\"wordCount\":553,\"commentCount\":0,\"articleSection\":[\"Mobilit\u00e4t\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/technologieregion-karlsruhe-stellt-ihr-mobilitatsportal-vor\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/technologieregion-karlsruhe-stellt-ihr-mobilitatsportal-vor\\\/\",\"url\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/technologieregion-karlsruhe-stellt-ihr-mobilitatsportal-vor\\\/\",\"name\":\"TechnologieRegion Karlsruhe stellt ihr Mobilit\u00e4tsportal vor - PAMINA Business Club\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/#website\"},\"datePublished\":\"2015-08-13T13:17:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/#\\\/schema\\\/person\\\/9ab02536dbdbc5e3ef40bbc3452c8c69\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/technologieregion-karlsruhe-stellt-ihr-mobilitatsportal-vor\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/technologieregion-karlsruhe-stellt-ihr-mobilitatsportal-vor\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/technologieregion-karlsruhe-stellt-ihr-mobilitatsportal-vor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TechnologieRegion Karlsruhe stellt ihr Mobilit\u00e4tsportal vor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/#website\",\"url\":\"https:\\\/\\\/www.pamina-business.com\\\/\",\"name\":\"PAMINA Business Club\",\"description\":\"Un site utilisant WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pamina-business.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/#\\\/schema\\\/person\\\/9ab02536dbdbc5e3ef40bbc3452c8c69\",\"name\":\"Monique STUTZMANN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc1c3adf9a9f6e969d3da7b6b34ec66f5f4a6844dfc9145380a75e42cd91882e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc1c3adf9a9f6e969d3da7b6b34ec66f5f4a6844dfc9145380a75e42cd91882e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc1c3adf9a9f6e969d3da7b6b34ec66f5f4a6844dfc9145380a75e42cd91882e?s=96&d=mm&r=g\",\"caption\":\"Monique STUTZMANN\"},\"url\":\"https:\\\/\\\/www.pamina-business.com\\\/de\\\/author\\\/monique\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TechnologieRegion Karlsruhe stellt ihr Mobilit\u00e4tsportal vor - PAMINA Business Club","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.pamina-business.com\/de\/technologieregion-karlsruhe-stellt-ihr-mobilitatsportal-vor\/","og_locale":"de_DE","og_type":"article","og_title":"TechnologieRegion Karlsruhe stellt ihr Mobilit\u00e4tsportal vor - PAMINA Business Club","og_description":"\u00a0 Wo rollt, klemmt, steht der Verkehr? Wie sehen meine M\u00f6glichkeiten zum Parken oder Umsteigen aus, welche Baustellen und Geschwindigkeitsbegrenzungen erwarten mich? All diese und weitere Fragen kann das Mobilit\u00e4tsportal der TechnologieRegion Karlsruhe (TRK) Pendlern und heutigen sowie potenziellen k\u00fcnftigen B\u00fcrgerinnen und B\u00fcrgern auf www.mobilitaet.trk.de beantworten &#8211; \u00fcberwiegend in Echtzeit. Der Verkehrsfluss wird im Drei-Minuten-Takt [&hellip;]","og_url":"http:\/\/www.pamina-business.com\/de\/technologieregion-karlsruhe-stellt-ihr-mobilitatsportal-vor\/","og_site_name":"PAMINA Business Club","article_published_time":"2015-08-13T13:17:19+00:00","author":"Monique STUTZMANN","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Monique STUTZMANN","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.pamina-business.com\/de\/technologieregion-karlsruhe-stellt-ihr-mobilitatsportal-vor\/#article","isPartOf":{"@id":"http:\/\/www.pamina-business.com\/de\/technologieregion-karlsruhe-stellt-ihr-mobilitatsportal-vor\/"},"author":{"name":"Monique STUTZMANN","@id":"https:\/\/www.pamina-business.com\/#\/schema\/person\/9ab02536dbdbc5e3ef40bbc3452c8c69"},"headline":"TechnologieRegion Karlsruhe stellt ihr Mobilit\u00e4tsportal vor","datePublished":"2015-08-13T13:17:19+00:00","mainEntityOfPage":{"@id":"http:\/\/www.pamina-business.com\/de\/technologieregion-karlsruhe-stellt-ihr-mobilitatsportal-vor\/"},"wordCount":553,"commentCount":0,"articleSection":["Mobilit\u00e4t"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/www.pamina-business.com\/de\/technologieregion-karlsruhe-stellt-ihr-mobilitatsportal-vor\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/www.pamina-business.com\/de\/technologieregion-karlsruhe-stellt-ihr-mobilitatsportal-vor\/","url":"http:\/\/www.pamina-business.com\/de\/technologieregion-karlsruhe-stellt-ihr-mobilitatsportal-vor\/","name":"TechnologieRegion Karlsruhe stellt ihr Mobilit\u00e4tsportal vor - PAMINA Business Club","isPartOf":{"@id":"https:\/\/www.pamina-business.com\/#website"},"datePublished":"2015-08-13T13:17:19+00:00","author":{"@id":"https:\/\/www.pamina-business.com\/#\/schema\/person\/9ab02536dbdbc5e3ef40bbc3452c8c69"},"breadcrumb":{"@id":"http:\/\/www.pamina-business.com\/de\/technologieregion-karlsruhe-stellt-ihr-mobilitatsportal-vor\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.pamina-business.com\/de\/technologieregion-karlsruhe-stellt-ihr-mobilitatsportal-vor\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.pamina-business.com\/de\/technologieregion-karlsruhe-stellt-ihr-mobilitatsportal-vor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/www.pamina-business.com\/de\/"},{"@type":"ListItem","position":2,"name":"TechnologieRegion Karlsruhe stellt ihr Mobilit\u00e4tsportal vor"}]},{"@type":"WebSite","@id":"https:\/\/www.pamina-business.com\/#website","url":"https:\/\/www.pamina-business.com\/","name":"PAMINA Business Club","description":"Un site utilisant WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pamina-business.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.pamina-business.com\/#\/schema\/person\/9ab02536dbdbc5e3ef40bbc3452c8c69","name":"Monique STUTZMANN","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/cc1c3adf9a9f6e969d3da7b6b34ec66f5f4a6844dfc9145380a75e42cd91882e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cc1c3adf9a9f6e969d3da7b6b34ec66f5f4a6844dfc9145380a75e42cd91882e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cc1c3adf9a9f6e969d3da7b6b34ec66f5f4a6844dfc9145380a75e42cd91882e?s=96&d=mm&r=g","caption":"Monique STUTZMANN"},"url":"https:\/\/www.pamina-business.com\/de\/author\/monique\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/posts\/770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/comments?post=770"}],"version-history":[{"count":3,"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/posts\/770\/revisions"}],"predecessor-version":[{"id":773,"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/posts\/770\/revisions\/773"}],"wp:attachment":[{"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/media?parent=770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/categories?post=770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/tags?post=770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}