{"id":427,"date":"2015-03-26T14:01:28","date_gmt":"2015-03-26T14:01:28","guid":{"rendered":"http:\/\/www.pamina-business.com\/?p=427"},"modified":"2015-03-23T14:04:45","modified_gmt":"2015-03-23T14:04:45","slug":"regionalkonferenz-der-technologieregion-karlsruhe-grenzuberschreitende-themenn","status":"publish","type":"post","link":"https:\/\/www.pamina-business.com\/de\/regionalkonferenz-der-technologieregion-karlsruhe-grenzuberschreitende-themenn\/","title":{"rendered":"Regionalkonferenz der TechnologieRegion Karlsruhe : grenz\u00fcberschreitende Themenn"},"content":{"rendered":"<p class=\"bodytext\"><strong>Grenz\u00fcberschreitender \u00d6PNV und Breitbandversorgung im Mittelpunkt der Gespr\u00e4che<\/strong><\/p>\n<p class=\"bodytext\">Die Regionalkonferenz der TechnologieRegion Karlsruhe (TRK) diskutierte auf ihrer Sitzung vom 11. M\u00e4rz 2015 den grenz\u00fcberschreitenden \u00f6ffentlichen Personennahverkehr am Oberrhein im Kontext der Fachkr\u00e4ftesicherung. \u201eDie bestehende Kooperation der IHK Karlsruhe mit den franz\u00f6sischen Kammern CCI Alsace und CCI Strasbourg et du Bas-Rhin im Projekt \u201aWirtschaft macht Schule\u2018 ist gut\u201c, so der Vorsitzende der Regionalkonferenz und IHK-Pr\u00e4sident Wolfgang Grenke, \u201eaber wir brauchen auch dringend die entsprechende Infrastruktur, damit die Jugendlichen \u00fcberhaupt zu uns kommen k\u00f6nnen, um hier zu arbeiten oder eine Ausbildung zu machen.\u201c<\/p>\n<p class=\"bodytext\">Eine fl\u00e4chendeckende Breitbandversorgung in der TechnologieRegion Karlsruhe steht zudem an vorderster Stelle bei den Erwartungen der Wirtschaft an die Politik. Die digitale Infrastruktur stellt einen wesentlichen Standortfaktor f\u00fcr die zunehmend vernetzte und technologieintensive Wirtschaft dar. Gerade in Zusammenhang mit Industrie 4.0 ist dieser Faktor entscheidend. \u201eBreitbandverbindungen m\u00fcssen massiv ausgebaut werden. Eine digitale Infrastruktur geh\u00f6rt heutzutage in jedes Haus, in jedes B\u00fcrogeb\u00e4ude, in jeden Betrieb selbstverst\u00e4ndlich mit dazu, genauso wie eine Strom-, Zu- und Abwasserleitung, ein Telefon und eine Gas- oder Fernw\u00e4rmeleitung. Wer kein schnelles Internet hat, ist vom Wettbewerb abgeschnitten.\u201c, betont IHK-Hauptgesch\u00e4ftsf\u00fchrer Prof. Hans-Peter Mengele.<\/p>\n<p class=\"bodytext\">Durch den Landeswettbewerb \u201eRegioWin\u201c hat die TechnologieRegion Karlsruhe eine erhebliche \u00d6ffentlichkeitswahrnehmung erfahren. \u201eDiese Dynamik soll aufgenommen und f\u00fcr weitere Schritte genutzt werden.\u201c, so der TRK-Vorsitzende, Oberb\u00fcrgermeister Dr. Frank Mentrup. Mit dem Regionalen Mobilit\u00e4tsverbund \u201eRegioMOVE\u201c und \u201eefeuCampus\u201c wurden zwei der drei eingereichten Leuchtturmprojekte pr\u00e4miert und erfahren eine F\u00f6rderquote aus EFRE- und Landesmitteln von insgesamt 70 Prozent.<\/p>\n<p class=\"bodytext\">\n<p class=\"bodytext\">Quelle : Newsletter der TechnologieRegion Karlsruhe \/ Ausgabe N \u00b0 2 \/ M\u00e4rz 2015<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grenz\u00fcberschreitender \u00d6PNV und Breitbandversorgung im Mittelpunkt der Gespr\u00e4che Die Regionalkonferenz der TechnologieRegion Karlsruhe (TRK) diskutierte auf ihrer Sitzung vom 11. M\u00e4rz 2015 den grenz\u00fcberschreitenden \u00f6ffentlichen Personennahverkehr am Oberrhein im Kontext der Fachkr\u00e4ftesicherung. \u201eDie bestehende Kooperation der IHK Karlsruhe mit den franz\u00f6sischen Kammern CCI Alsace und CCI Strasbourg et du Bas-Rhin im Projekt \u201aWirtschaft macht Schule\u2018 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[],"class_list":["post-427","post","type-post","status-publish","format-standard","hentry","category-mobilitat-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Regionalkonferenz der TechnologieRegion Karlsruhe : grenz\u00fcberschreitende Themenn - PAMINA Business Club<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.pamina-business.com\/de\/regionalkonferenz-der-technologieregion-karlsruhe-grenzuberschreitende-themenn\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Regionalkonferenz der TechnologieRegion Karlsruhe : grenz\u00fcberschreitende Themenn - PAMINA Business Club\" \/>\n<meta property=\"og:description\" content=\"Grenz\u00fcberschreitender \u00d6PNV und Breitbandversorgung im Mittelpunkt der Gespr\u00e4che Die Regionalkonferenz der TechnologieRegion Karlsruhe (TRK) diskutierte auf ihrer Sitzung vom 11. M\u00e4rz 2015 den grenz\u00fcberschreitenden \u00f6ffentlichen Personennahverkehr am Oberrhein im Kontext der Fachkr\u00e4ftesicherung. \u201eDie bestehende Kooperation der IHK Karlsruhe mit den franz\u00f6sischen Kammern CCI Alsace und CCI Strasbourg et du Bas-Rhin im Projekt \u201aWirtschaft macht Schule\u2018 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.pamina-business.com\/de\/regionalkonferenz-der-technologieregion-karlsruhe-grenzuberschreitende-themenn\/\" \/>\n<meta property=\"og:site_name\" content=\"PAMINA Business Club\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-26T14:01:28+00:00\" \/>\n<meta name=\"author\" content=\"Monique STUTZMANN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Monique STUTZMANN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/regionalkonferenz-der-technologieregion-karlsruhe-grenzuberschreitende-themenn\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/regionalkonferenz-der-technologieregion-karlsruhe-grenzuberschreitende-themenn\\\/\"},\"author\":{\"name\":\"Monique STUTZMANN\",\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/#\\\/schema\\\/person\\\/9ab02536dbdbc5e3ef40bbc3452c8c69\"},\"headline\":\"Regionalkonferenz der TechnologieRegion Karlsruhe : grenz\u00fcberschreitende Themenn\",\"datePublished\":\"2015-03-26T14:01:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/regionalkonferenz-der-technologieregion-karlsruhe-grenzuberschreitende-themenn\\\/\"},\"wordCount\":276,\"commentCount\":0,\"articleSection\":[\"Mobilit\u00e4t\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/regionalkonferenz-der-technologieregion-karlsruhe-grenzuberschreitende-themenn\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/regionalkonferenz-der-technologieregion-karlsruhe-grenzuberschreitende-themenn\\\/\",\"url\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/regionalkonferenz-der-technologieregion-karlsruhe-grenzuberschreitende-themenn\\\/\",\"name\":\"Regionalkonferenz der TechnologieRegion Karlsruhe : grenz\u00fcberschreitende Themenn - PAMINA Business Club\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/#website\"},\"datePublished\":\"2015-03-26T14:01:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/#\\\/schema\\\/person\\\/9ab02536dbdbc5e3ef40bbc3452c8c69\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/regionalkonferenz-der-technologieregion-karlsruhe-grenzuberschreitende-themenn\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/regionalkonferenz-der-technologieregion-karlsruhe-grenzuberschreitende-themenn\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/regionalkonferenz-der-technologieregion-karlsruhe-grenzuberschreitende-themenn\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.pamina-business.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Regionalkonferenz der TechnologieRegion Karlsruhe : grenz\u00fcberschreitende Themenn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/#website\",\"url\":\"https:\\\/\\\/www.pamina-business.com\\\/\",\"name\":\"PAMINA Business Club\",\"description\":\"Un site utilisant WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pamina-business.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/#\\\/schema\\\/person\\\/9ab02536dbdbc5e3ef40bbc3452c8c69\",\"name\":\"Monique STUTZMANN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc1c3adf9a9f6e969d3da7b6b34ec66f5f4a6844dfc9145380a75e42cd91882e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc1c3adf9a9f6e969d3da7b6b34ec66f5f4a6844dfc9145380a75e42cd91882e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc1c3adf9a9f6e969d3da7b6b34ec66f5f4a6844dfc9145380a75e42cd91882e?s=96&d=mm&r=g\",\"caption\":\"Monique STUTZMANN\"},\"url\":\"https:\\\/\\\/www.pamina-business.com\\\/de\\\/author\\\/monique\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Regionalkonferenz der TechnologieRegion Karlsruhe : grenz\u00fcberschreitende Themenn - PAMINA Business Club","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.pamina-business.com\/de\/regionalkonferenz-der-technologieregion-karlsruhe-grenzuberschreitende-themenn\/","og_locale":"de_DE","og_type":"article","og_title":"Regionalkonferenz der TechnologieRegion Karlsruhe : grenz\u00fcberschreitende Themenn - PAMINA Business Club","og_description":"Grenz\u00fcberschreitender \u00d6PNV und Breitbandversorgung im Mittelpunkt der Gespr\u00e4che Die Regionalkonferenz der TechnologieRegion Karlsruhe (TRK) diskutierte auf ihrer Sitzung vom 11. M\u00e4rz 2015 den grenz\u00fcberschreitenden \u00f6ffentlichen Personennahverkehr am Oberrhein im Kontext der Fachkr\u00e4ftesicherung. \u201eDie bestehende Kooperation der IHK Karlsruhe mit den franz\u00f6sischen Kammern CCI Alsace und CCI Strasbourg et du Bas-Rhin im Projekt \u201aWirtschaft macht Schule\u2018 [&hellip;]","og_url":"http:\/\/www.pamina-business.com\/de\/regionalkonferenz-der-technologieregion-karlsruhe-grenzuberschreitende-themenn\/","og_site_name":"PAMINA Business Club","article_published_time":"2015-03-26T14:01:28+00:00","author":"Monique STUTZMANN","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Monique STUTZMANN","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.pamina-business.com\/de\/regionalkonferenz-der-technologieregion-karlsruhe-grenzuberschreitende-themenn\/#article","isPartOf":{"@id":"http:\/\/www.pamina-business.com\/de\/regionalkonferenz-der-technologieregion-karlsruhe-grenzuberschreitende-themenn\/"},"author":{"name":"Monique STUTZMANN","@id":"https:\/\/www.pamina-business.com\/#\/schema\/person\/9ab02536dbdbc5e3ef40bbc3452c8c69"},"headline":"Regionalkonferenz der TechnologieRegion Karlsruhe : grenz\u00fcberschreitende Themenn","datePublished":"2015-03-26T14:01:28+00:00","mainEntityOfPage":{"@id":"http:\/\/www.pamina-business.com\/de\/regionalkonferenz-der-technologieregion-karlsruhe-grenzuberschreitende-themenn\/"},"wordCount":276,"commentCount":0,"articleSection":["Mobilit\u00e4t"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/www.pamina-business.com\/de\/regionalkonferenz-der-technologieregion-karlsruhe-grenzuberschreitende-themenn\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/www.pamina-business.com\/de\/regionalkonferenz-der-technologieregion-karlsruhe-grenzuberschreitende-themenn\/","url":"http:\/\/www.pamina-business.com\/de\/regionalkonferenz-der-technologieregion-karlsruhe-grenzuberschreitende-themenn\/","name":"Regionalkonferenz der TechnologieRegion Karlsruhe : grenz\u00fcberschreitende Themenn - PAMINA Business Club","isPartOf":{"@id":"https:\/\/www.pamina-business.com\/#website"},"datePublished":"2015-03-26T14:01:28+00:00","author":{"@id":"https:\/\/www.pamina-business.com\/#\/schema\/person\/9ab02536dbdbc5e3ef40bbc3452c8c69"},"breadcrumb":{"@id":"http:\/\/www.pamina-business.com\/de\/regionalkonferenz-der-technologieregion-karlsruhe-grenzuberschreitende-themenn\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.pamina-business.com\/de\/regionalkonferenz-der-technologieregion-karlsruhe-grenzuberschreitende-themenn\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.pamina-business.com\/de\/regionalkonferenz-der-technologieregion-karlsruhe-grenzuberschreitende-themenn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.pamina-business.com\/de\/"},{"@type":"ListItem","position":2,"name":"Regionalkonferenz der TechnologieRegion Karlsruhe : grenz\u00fcberschreitende Themenn"}]},{"@type":"WebSite","@id":"https:\/\/www.pamina-business.com\/#website","url":"https:\/\/www.pamina-business.com\/","name":"PAMINA Business Club","description":"Un site utilisant WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pamina-business.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.pamina-business.com\/#\/schema\/person\/9ab02536dbdbc5e3ef40bbc3452c8c69","name":"Monique STUTZMANN","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/cc1c3adf9a9f6e969d3da7b6b34ec66f5f4a6844dfc9145380a75e42cd91882e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cc1c3adf9a9f6e969d3da7b6b34ec66f5f4a6844dfc9145380a75e42cd91882e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cc1c3adf9a9f6e969d3da7b6b34ec66f5f4a6844dfc9145380a75e42cd91882e?s=96&d=mm&r=g","caption":"Monique STUTZMANN"},"url":"https:\/\/www.pamina-business.com\/de\/author\/monique\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/posts\/427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/comments?post=427"}],"version-history":[{"count":1,"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/posts\/427\/revisions"}],"predecessor-version":[{"id":428,"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/posts\/427\/revisions\/428"}],"wp:attachment":[{"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/media?parent=427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/categories?post=427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/tags?post=427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}