{"id":2593,"date":"2017-06-28T12:09:16","date_gmt":"2017-06-28T12:09:16","guid":{"rendered":"http:\/\/www.pamina-business.com\/?p=2593"},"modified":"2017-06-27T12:12:37","modified_gmt":"2017-06-27T12:12:37","slug":"grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017","status":"publish","type":"post","link":"https:\/\/www.pamina-business.com\/de\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\/","title":{"rendered":"Grenz\u00fcberschreitendes Fahrradfest am Rhein im Rahmen des 40j\u00e4hrigen Jubil\u00e4ums der F\u00e4hre \u201eDrusus\u201c am 9. Juli 2017"},"content":{"rendered":"<section id=\"mainSection\">\n<div class=\"fmodele tpl_fiche\">\n<div class=\"agendas-fiche\">\n<article class=\"media\">\n<div class=\"media-object\"><img decoding=\"async\" src=\"http:\/\/www.eurodistrict-pamina.eu\/globalflexit\/images\/img_base\/agendas\/835_556_1_20130514-velopamina-031-dgj.jpg\" alt=\"Radfahrer am Rhein\" \/><\/div>\n<div class=\"media-body\"><br class=\"media-heading\" \/><\/p>\n<div class=\"contenu\">Am 9. Juli 2017 wird das in 2017 stattfindende 40-j\u00e4hrige Jubil\u00e4um der Rheinf\u00e4hre \u201eDrusus\u201c zwischen Greffern und Drusenheim gefeiert. Unter Federf\u00fchrung des Conseil D\u00e9partemental du Bas-Rhin findet zu diesem Anlass ein grenz\u00fcberschreitendes Fahrradfest statt.<\/p>\n<p>Fr\u00e9d\u00e9ric Bierry, Pr\u00e4sident vom Conseil D\u00e9partemental du Bas-Rhin, wird an diesem Tag den \u201etausendsten Radweg- Kilometer\u201c im Bas-Rhin sowie die neue Kreuzrhein-Br\u00fccke in Drusenheim einweihen. Des Weiteren wird das 40-j\u00e4hrige Jubil\u00e4um der Motorf\u00e4hre \u201eDrusus\u201c in Anwesenheit eines Vertreters des Regierungspr\u00e4sidiums Freiburg gefeiert und es werden zahlreiche Sportaktivit\u00e4ten und kulturelle Animationen angeboten.<\/p>\n<p>Die Bewirtung erfolgt durch die Vereine aus Drusenheim.<\/p>\n<p>Die Veranstaltung bildet ein gemeinsames Projekt mit dem am 1. und 2. Juliwochenende stattfinden Fest <a href=\"http:\/\/www.eurodistrict-pamina.eu\/de\/aktivitaeten\/begegnungen-und-mobilitat-am-rhein_-d.html#.WSLRKjHgpqM\">&#8222;Begegnungen und Mobilit\u00e4t am Rhein&#8220;<\/a>.<\/p>\n<div>\n<span class=\"legende\"><em>Photo<\/em>: \u00a9 Denis Guichot \/ CD 67<\/span><\/div>\n<\/div>\n<div><em>Quelle<\/em> : <a href=\"http:\/\/www.eurodistrict-pamina.eu\">www.eurodistrict-pamina.eu<\/a><\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Am 9. Juli 2017 wird das in 2017 stattfindende 40-j\u00e4hrige Jubil\u00e4um der Rheinf\u00e4hre \u201eDrusus\u201c zwischen Greffern und Drusenheim gefeiert. Unter Federf\u00fchrung des Conseil D\u00e9partemental du Bas-Rhin findet zu diesem Anlass ein grenz\u00fcberschreitendes Fahrradfest statt. Fr\u00e9d\u00e9ric Bierry, Pr\u00e4sident vom Conseil D\u00e9partemental du Bas-Rhin, wird an diesem Tag den \u201etausendsten Radweg- Kilometer\u201c im Bas-Rhin sowie die neue [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59,62],"tags":[],"class_list":["post-2593","post","type-post","status-publish","format-standard","hentry","category-ereignisse-de","category-mobilitat-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grenz\u00fcberschreitendes Fahrradfest am Rhein im Rahmen des 40j\u00e4hrigen Jubil\u00e4ums der F\u00e4hre \u201eDrusus\u201c am 9. Juli 2017 - PAMINA Business Club<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pamina-business.com\/de\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grenz\u00fcberschreitendes Fahrradfest am Rhein im Rahmen des 40j\u00e4hrigen Jubil\u00e4ums der F\u00e4hre \u201eDrusus\u201c am 9. Juli 2017 - PAMINA Business Club\" \/>\n<meta property=\"og:description\" content=\"Am 9. Juli 2017 wird das in 2017 stattfindende 40-j\u00e4hrige Jubil\u00e4um der Rheinf\u00e4hre \u201eDrusus\u201c zwischen Greffern und Drusenheim gefeiert. Unter Federf\u00fchrung des Conseil D\u00e9partemental du Bas-Rhin findet zu diesem Anlass ein grenz\u00fcberschreitendes Fahrradfest statt. Fr\u00e9d\u00e9ric Bierry, Pr\u00e4sident vom Conseil D\u00e9partemental du Bas-Rhin, wird an diesem Tag den \u201etausendsten Radweg- Kilometer\u201c im Bas-Rhin sowie die neue [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pamina-business.com\/de\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"PAMINA Business Club\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-28T12:09:16+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.eurodistrict-pamina.eu\/globalflexit\/images\/img_base\/agendas\/835_556_1_20130514-velopamina-031-dgj.jpg\" \/>\n<meta name=\"author\" content=\"Monique STUTZMANN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Monique STUTZMANN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/de\\\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/de\\\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\\\/\"},\"author\":{\"name\":\"Monique STUTZMANN\",\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/#\\\/schema\\\/person\\\/9ab02536dbdbc5e3ef40bbc3452c8c69\"},\"headline\":\"Grenz\u00fcberschreitendes Fahrradfest am Rhein im Rahmen des 40j\u00e4hrigen Jubil\u00e4ums der F\u00e4hre \u201eDrusus\u201c am 9. Juli 2017\",\"datePublished\":\"2017-06-28T12:09:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/de\\\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\\\/\"},\"wordCount\":151,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/de\\\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.eurodistrict-pamina.eu\\\/globalflexit\\\/images\\\/img_base\\\/agendas\\\/835_556_1_20130514-velopamina-031-dgj.jpg\",\"articleSection\":[\"Ereignisse\",\"Mobilit\u00e4t\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.pamina-business.com\\\/de\\\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/de\\\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\\\/\",\"url\":\"https:\\\/\\\/www.pamina-business.com\\\/de\\\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\\\/\",\"name\":\"Grenz\u00fcberschreitendes Fahrradfest am Rhein im Rahmen des 40j\u00e4hrigen Jubil\u00e4ums der F\u00e4hre \u201eDrusus\u201c am 9. Juli 2017 - PAMINA Business Club\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/de\\\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/de\\\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.eurodistrict-pamina.eu\\\/globalflexit\\\/images\\\/img_base\\\/agendas\\\/835_556_1_20130514-velopamina-031-dgj.jpg\",\"datePublished\":\"2017-06-28T12:09:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/#\\\/schema\\\/person\\\/9ab02536dbdbc5e3ef40bbc3452c8c69\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/de\\\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pamina-business.com\\\/de\\\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/de\\\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.eurodistrict-pamina.eu\\\/globalflexit\\\/images\\\/img_base\\\/agendas\\\/835_556_1_20130514-velopamina-031-dgj.jpg\",\"contentUrl\":\"http:\\\/\\\/www.eurodistrict-pamina.eu\\\/globalflexit\\\/images\\\/img_base\\\/agendas\\\/835_556_1_20130514-velopamina-031-dgj.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/de\\\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.pamina-business.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grenz\u00fcberschreitendes Fahrradfest am Rhein im Rahmen des 40j\u00e4hrigen Jubil\u00e4ums der F\u00e4hre \u201eDrusus\u201c am 9. Juli 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/#website\",\"url\":\"https:\\\/\\\/www.pamina-business.com\\\/\",\"name\":\"PAMINA Business Club\",\"description\":\"Un site utilisant WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pamina-business.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/#\\\/schema\\\/person\\\/9ab02536dbdbc5e3ef40bbc3452c8c69\",\"name\":\"Monique STUTZMANN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc1c3adf9a9f6e969d3da7b6b34ec66f5f4a6844dfc9145380a75e42cd91882e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc1c3adf9a9f6e969d3da7b6b34ec66f5f4a6844dfc9145380a75e42cd91882e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc1c3adf9a9f6e969d3da7b6b34ec66f5f4a6844dfc9145380a75e42cd91882e?s=96&d=mm&r=g\",\"caption\":\"Monique STUTZMANN\"},\"url\":\"https:\\\/\\\/www.pamina-business.com\\\/de\\\/author\\\/monique\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grenz\u00fcberschreitendes Fahrradfest am Rhein im Rahmen des 40j\u00e4hrigen Jubil\u00e4ums der F\u00e4hre \u201eDrusus\u201c am 9. Juli 2017 - PAMINA Business Club","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pamina-business.com\/de\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\/","og_locale":"de_DE","og_type":"article","og_title":"Grenz\u00fcberschreitendes Fahrradfest am Rhein im Rahmen des 40j\u00e4hrigen Jubil\u00e4ums der F\u00e4hre \u201eDrusus\u201c am 9. Juli 2017 - PAMINA Business Club","og_description":"Am 9. Juli 2017 wird das in 2017 stattfindende 40-j\u00e4hrige Jubil\u00e4um der Rheinf\u00e4hre \u201eDrusus\u201c zwischen Greffern und Drusenheim gefeiert. Unter Federf\u00fchrung des Conseil D\u00e9partemental du Bas-Rhin findet zu diesem Anlass ein grenz\u00fcberschreitendes Fahrradfest statt. Fr\u00e9d\u00e9ric Bierry, Pr\u00e4sident vom Conseil D\u00e9partemental du Bas-Rhin, wird an diesem Tag den \u201etausendsten Radweg- Kilometer\u201c im Bas-Rhin sowie die neue [&hellip;]","og_url":"https:\/\/www.pamina-business.com\/de\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\/","og_site_name":"PAMINA Business Club","article_published_time":"2017-06-28T12:09:16+00:00","og_image":[{"url":"http:\/\/www.eurodistrict-pamina.eu\/globalflexit\/images\/img_base\/agendas\/835_556_1_20130514-velopamina-031-dgj.jpg","type":"","width":"","height":""}],"author":"Monique STUTZMANN","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Monique STUTZMANN","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pamina-business.com\/de\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\/#article","isPartOf":{"@id":"https:\/\/www.pamina-business.com\/de\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\/"},"author":{"name":"Monique STUTZMANN","@id":"https:\/\/www.pamina-business.com\/#\/schema\/person\/9ab02536dbdbc5e3ef40bbc3452c8c69"},"headline":"Grenz\u00fcberschreitendes Fahrradfest am Rhein im Rahmen des 40j\u00e4hrigen Jubil\u00e4ums der F\u00e4hre \u201eDrusus\u201c am 9. Juli 2017","datePublished":"2017-06-28T12:09:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pamina-business.com\/de\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\/"},"wordCount":151,"commentCount":0,"image":{"@id":"https:\/\/www.pamina-business.com\/de\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\/#primaryimage"},"thumbnailUrl":"http:\/\/www.eurodistrict-pamina.eu\/globalflexit\/images\/img_base\/agendas\/835_556_1_20130514-velopamina-031-dgj.jpg","articleSection":["Ereignisse","Mobilit\u00e4t"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pamina-business.com\/de\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pamina-business.com\/de\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\/","url":"https:\/\/www.pamina-business.com\/de\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\/","name":"Grenz\u00fcberschreitendes Fahrradfest am Rhein im Rahmen des 40j\u00e4hrigen Jubil\u00e4ums der F\u00e4hre \u201eDrusus\u201c am 9. Juli 2017 - PAMINA Business Club","isPartOf":{"@id":"https:\/\/www.pamina-business.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pamina-business.com\/de\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\/#primaryimage"},"image":{"@id":"https:\/\/www.pamina-business.com\/de\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\/#primaryimage"},"thumbnailUrl":"http:\/\/www.eurodistrict-pamina.eu\/globalflexit\/images\/img_base\/agendas\/835_556_1_20130514-velopamina-031-dgj.jpg","datePublished":"2017-06-28T12:09:16+00:00","author":{"@id":"https:\/\/www.pamina-business.com\/#\/schema\/person\/9ab02536dbdbc5e3ef40bbc3452c8c69"},"breadcrumb":{"@id":"https:\/\/www.pamina-business.com\/de\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pamina-business.com\/de\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.pamina-business.com\/de\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\/#primaryimage","url":"http:\/\/www.eurodistrict-pamina.eu\/globalflexit\/images\/img_base\/agendas\/835_556_1_20130514-velopamina-031-dgj.jpg","contentUrl":"http:\/\/www.eurodistrict-pamina.eu\/globalflexit\/images\/img_base\/agendas\/835_556_1_20130514-velopamina-031-dgj.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pamina-business.com\/de\/grenzuberschreitendes-fahrradfest-am-rhein-im-rahmen-des-40jahrigen-jubilaums-der-fahre-drusus-am-9-juli-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.pamina-business.com\/de\/"},{"@type":"ListItem","position":2,"name":"Grenz\u00fcberschreitendes Fahrradfest am Rhein im Rahmen des 40j\u00e4hrigen Jubil\u00e4ums der F\u00e4hre \u201eDrusus\u201c am 9. Juli 2017"}]},{"@type":"WebSite","@id":"https:\/\/www.pamina-business.com\/#website","url":"https:\/\/www.pamina-business.com\/","name":"PAMINA Business Club","description":"Un site utilisant WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pamina-business.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.pamina-business.com\/#\/schema\/person\/9ab02536dbdbc5e3ef40bbc3452c8c69","name":"Monique STUTZMANN","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/cc1c3adf9a9f6e969d3da7b6b34ec66f5f4a6844dfc9145380a75e42cd91882e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cc1c3adf9a9f6e969d3da7b6b34ec66f5f4a6844dfc9145380a75e42cd91882e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cc1c3adf9a9f6e969d3da7b6b34ec66f5f4a6844dfc9145380a75e42cd91882e?s=96&d=mm&r=g","caption":"Monique STUTZMANN"},"url":"https:\/\/www.pamina-business.com\/de\/author\/monique\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/posts\/2593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/comments?post=2593"}],"version-history":[{"count":1,"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/posts\/2593\/revisions"}],"predecessor-version":[{"id":2594,"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/posts\/2593\/revisions\/2594"}],"wp:attachment":[{"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/media?parent=2593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/categories?post=2593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/tags?post=2593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}