{"id":1520,"date":"2016-04-26T08:00:20","date_gmt":"2016-04-26T08:00:20","guid":{"rendered":"http:\/\/www.pamina-business.com\/?p=1520"},"modified":"2016-04-19T08:04:08","modified_gmt":"2016-04-19T08:04:08","slug":"de-nouvelles-passerelles-entre-rhin-et-lauter","status":"publish","type":"post","link":"http:\/\/www.pamina-business.com\/de\/de-nouvelles-passerelles-entre-rhin-et-lauter\/","title":{"rendered":"De nouvelles passerelles entre Rhin et Lauter"},"content":{"rendered":"<p><a href=\"http:\/\/www.pamina-business.com\/wp-content\/uploads\/2016\/04\/passerelle.jpg\" rel=\"attachment wp-att-1522\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1522\" src=\"http:\/\/www.pamina-business.com\/wp-content\/uploads\/2016\/04\/passerelle.jpg\" alt=\"passerelle\" width=\"150\" height=\"56\" \/><\/a><\/p>\n<p>Apr\u00e8s plusieurs mois de travail le Forum Trans-PAMINA a achev\u00e9 son livre blanc \u00ab De nouvelles passerelles entre Rhin et Lauter \u00bb. La brochure dessine des perspectives pour la mise en place d\u2019un transport public transfrontalier dans l\u2019espace PAMINA.<\/p>\n<p>Le projet global d\u2019un syst\u00e8me de transport public futuriste d\u00e9velopp\u00e9 dans le livre blanc repose sur cinq composantes. D\u2019apr\u00e8s les auteurs, il s\u2019agit non seulement de r\u00e9activer la ligne ferroviaire \u00ab Rastatt \u2013 Wintersdorf \u2013 Roeschwoog \u2013 Haguenau \u00bb mais aussi de la compl\u00e9ter par un r\u00e9seau de bus et de voies ferr\u00e9es avec un cadencement horaire.<\/p>\n<p>Les cinq composantes :<br \/>\n1. Des lignes de bus Baden-Baden \u2013 Roeschwoog \u2013 (Haguenau) en cadencement horaire<br \/>\n2. Circulations entre Rastatt, Roeschwoog et Haguenau en cadencement horaire<br \/>\n3. Cadencement de la ligne ferroviaire Strasbourg \u2013 Roeschwoog \u2013 Lauterbourg jusqu\u2019\u00e0 W\u00f6rth (pr\u00e8s de Karlsruhe et Landau)<br \/>\n4. Am\u00e9lioration de la ligne ferroviaire Strasbourg \u2013 Haguenau \u2013 Wissembourg \u2013 Landau \u2013 Neustadt \/ Weinstra\u00dfe<br \/>\n5. Mise en place d\u2019une tarification transfrontali\u00e8re<\/p>\n<p>Le Pr\u00e9sident de l\u2019Eurodistrict, Fritz Brechtel (Landrat du Landkreis de Germersheim), se f\u00e9licite, dans la pr\u00e9face de la brochure, de l\u2019engagement civique de Trans-PAMINA et consid\u00e8re les propositions du livre blanc comme susceptibles d\u2019enrichir le d\u00e9bat public sur l\u2019enjeu des transports en commun transfrontaliers.<\/p>\n<p>Le livre blanc bilingue est disponible sur le site internet de Trans-PAMINA en version t\u00e9l\u00e9chargeable.<\/p>\n<p><a href=\"http:\/\/www.trans-pamina.eu\/IMG\/pdf\/weissbuch_livre_blanc_transpamina_2016.pdf\" target=\"_blank\">http:\/\/www.trans-pamina.eu\/IMG\/pdf\/weissbuch_livre_blanc_transpamina_2016.pdf<\/a><\/p>\n<p>Le Forum Trans-PAMINA se veut une alliance franco-allemande pour un r\u00e9seau attrayant de transports publics. Il est port\u00e9 par plusieurs organisations des deux c\u00f4t\u00e9s du Rhin :<\/p>\n<p>&#8211; Association des usagers des Transports Urbains de l\u2019agglom\u00e9ration strasbourgeoise (ASTUS)<br \/>\n&#8211; F\u00e9d\u00e9ration Nationale d\u2018Usagers des Transports (FNAUT Alsace)<br \/>\n&#8211; Fahrgastverband PRO BAHN<br \/>\n&#8211; Verkehrsclub Deutschland (VCD)<br \/>\n&#8211; B\u00fcrgeraktion Umweltschutz Zentrales Oberrheingebiet (BUZO)<br \/>\n&#8211; S\u00dcDPFALZ mobil e.V.<br \/>\n&#8211; Landesvereinigung Baden in Europa<\/p>\n<p><em>Source<\/em> : <a href=\"http:\/\/www.eurodistrict-pamina.eu\" target=\"_blank\">www.eurodistrict-pamina.eu<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s plusieurs mois de travail le Forum Trans-PAMINA a achev\u00e9 son livre blanc \u00ab De nouvelles passerelles entre Rhin et Lauter \u00bb. La brochure dessine des perspectives pour la mise en place d\u2019un transport public transfrontalier dans l\u2019espace PAMINA. Le projet global d\u2019un syst\u00e8me de transport public futuriste d\u00e9velopp\u00e9 dans le livre blanc repose sur [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-1520","post","type-post","status-publish","format-standard","hentry","category-mobilite-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>De nouvelles passerelles entre Rhin et Lauter - PAMINA Business Club<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.pamina-business.com\/de\/de-nouvelles-passerelles-entre-rhin-et-lauter\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De nouvelles passerelles entre Rhin et Lauter - PAMINA Business Club\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s plusieurs mois de travail le Forum Trans-PAMINA a achev\u00e9 son livre blanc \u00ab De nouvelles passerelles entre Rhin et Lauter \u00bb. La brochure dessine des perspectives pour la mise en place d\u2019un transport public transfrontalier dans l\u2019espace PAMINA. Le projet global d\u2019un syst\u00e8me de transport public futuriste d\u00e9velopp\u00e9 dans le livre blanc repose sur [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.pamina-business.com\/de\/de-nouvelles-passerelles-entre-rhin-et-lauter\/\" \/>\n<meta property=\"og:site_name\" content=\"PAMINA Business Club\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-26T08:00:20+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.pamina-business.com\/wp-content\/uploads\/2016\/04\/passerelle.jpg\" \/>\n<meta name=\"author\" content=\"Monique STUTZMANN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Monique STUTZMANN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/de-nouvelles-passerelles-entre-rhin-et-lauter\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/de-nouvelles-passerelles-entre-rhin-et-lauter\\\/\"},\"author\":{\"name\":\"Monique STUTZMANN\",\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/#\\\/schema\\\/person\\\/9ab02536dbdbc5e3ef40bbc3452c8c69\"},\"headline\":\"De nouvelles passerelles entre Rhin et Lauter\",\"datePublished\":\"2016-04-26T08:00:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/de-nouvelles-passerelles-entre-rhin-et-lauter\\\/\"},\"wordCount\":333,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/de-nouvelles-passerelles-entre-rhin-et-lauter\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.pamina-business.com\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/passerelle.jpg\",\"articleSection\":[\"Mobilit\u00e9\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/de-nouvelles-passerelles-entre-rhin-et-lauter\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/de-nouvelles-passerelles-entre-rhin-et-lauter\\\/\",\"url\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/de-nouvelles-passerelles-entre-rhin-et-lauter\\\/\",\"name\":\"De nouvelles passerelles entre Rhin et Lauter - PAMINA Business Club\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/de-nouvelles-passerelles-entre-rhin-et-lauter\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/de-nouvelles-passerelles-entre-rhin-et-lauter\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.pamina-business.com\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/passerelle.jpg\",\"datePublished\":\"2016-04-26T08:00:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/#\\\/schema\\\/person\\\/9ab02536dbdbc5e3ef40bbc3452c8c69\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/de-nouvelles-passerelles-entre-rhin-et-lauter\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/de-nouvelles-passerelles-entre-rhin-et-lauter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/de-nouvelles-passerelles-entre-rhin-et-lauter\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.pamina-business.com\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/passerelle.jpg\",\"contentUrl\":\"http:\\\/\\\/www.pamina-business.com\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/passerelle.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/de-nouvelles-passerelles-entre-rhin-et-lauter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.pamina-business.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"De nouvelles passerelles entre Rhin et Lauter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/#website\",\"url\":\"https:\\\/\\\/www.pamina-business.com\\\/\",\"name\":\"PAMINA Business Club\",\"description\":\"Un site utilisant WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pamina-business.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pamina-business.com\\\/#\\\/schema\\\/person\\\/9ab02536dbdbc5e3ef40bbc3452c8c69\",\"name\":\"Monique STUTZMANN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc1c3adf9a9f6e969d3da7b6b34ec66f5f4a6844dfc9145380a75e42cd91882e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc1c3adf9a9f6e969d3da7b6b34ec66f5f4a6844dfc9145380a75e42cd91882e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc1c3adf9a9f6e969d3da7b6b34ec66f5f4a6844dfc9145380a75e42cd91882e?s=96&d=mm&r=g\",\"caption\":\"Monique STUTZMANN\"},\"url\":\"http:\\\/\\\/www.pamina-business.com\\\/de\\\/author\\\/monique\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De nouvelles passerelles entre Rhin et Lauter - PAMINA Business Club","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.pamina-business.com\/de\/de-nouvelles-passerelles-entre-rhin-et-lauter\/","og_locale":"de_DE","og_type":"article","og_title":"De nouvelles passerelles entre Rhin et Lauter - PAMINA Business Club","og_description":"Apr\u00e8s plusieurs mois de travail le Forum Trans-PAMINA a achev\u00e9 son livre blanc \u00ab De nouvelles passerelles entre Rhin et Lauter \u00bb. La brochure dessine des perspectives pour la mise en place d\u2019un transport public transfrontalier dans l\u2019espace PAMINA. Le projet global d\u2019un syst\u00e8me de transport public futuriste d\u00e9velopp\u00e9 dans le livre blanc repose sur [&hellip;]","og_url":"http:\/\/www.pamina-business.com\/de\/de-nouvelles-passerelles-entre-rhin-et-lauter\/","og_site_name":"PAMINA Business Club","article_published_time":"2016-04-26T08:00:20+00:00","og_image":[{"url":"http:\/\/www.pamina-business.com\/wp-content\/uploads\/2016\/04\/passerelle.jpg","type":"","width":"","height":""}],"author":"Monique STUTZMANN","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Monique STUTZMANN","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.pamina-business.com\/de\/de-nouvelles-passerelles-entre-rhin-et-lauter\/#article","isPartOf":{"@id":"http:\/\/www.pamina-business.com\/de\/de-nouvelles-passerelles-entre-rhin-et-lauter\/"},"author":{"name":"Monique STUTZMANN","@id":"https:\/\/www.pamina-business.com\/#\/schema\/person\/9ab02536dbdbc5e3ef40bbc3452c8c69"},"headline":"De nouvelles passerelles entre Rhin et Lauter","datePublished":"2016-04-26T08:00:20+00:00","mainEntityOfPage":{"@id":"http:\/\/www.pamina-business.com\/de\/de-nouvelles-passerelles-entre-rhin-et-lauter\/"},"wordCount":333,"commentCount":0,"image":{"@id":"http:\/\/www.pamina-business.com\/de\/de-nouvelles-passerelles-entre-rhin-et-lauter\/#primaryimage"},"thumbnailUrl":"http:\/\/www.pamina-business.com\/wp-content\/uploads\/2016\/04\/passerelle.jpg","articleSection":["Mobilit\u00e9"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/www.pamina-business.com\/de\/de-nouvelles-passerelles-entre-rhin-et-lauter\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/www.pamina-business.com\/de\/de-nouvelles-passerelles-entre-rhin-et-lauter\/","url":"http:\/\/www.pamina-business.com\/de\/de-nouvelles-passerelles-entre-rhin-et-lauter\/","name":"De nouvelles passerelles entre Rhin et Lauter - PAMINA Business Club","isPartOf":{"@id":"https:\/\/www.pamina-business.com\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.pamina-business.com\/de\/de-nouvelles-passerelles-entre-rhin-et-lauter\/#primaryimage"},"image":{"@id":"http:\/\/www.pamina-business.com\/de\/de-nouvelles-passerelles-entre-rhin-et-lauter\/#primaryimage"},"thumbnailUrl":"http:\/\/www.pamina-business.com\/wp-content\/uploads\/2016\/04\/passerelle.jpg","datePublished":"2016-04-26T08:00:20+00:00","author":{"@id":"https:\/\/www.pamina-business.com\/#\/schema\/person\/9ab02536dbdbc5e3ef40bbc3452c8c69"},"breadcrumb":{"@id":"http:\/\/www.pamina-business.com\/de\/de-nouvelles-passerelles-entre-rhin-et-lauter\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.pamina-business.com\/de\/de-nouvelles-passerelles-entre-rhin-et-lauter\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"http:\/\/www.pamina-business.com\/de\/de-nouvelles-passerelles-entre-rhin-et-lauter\/#primaryimage","url":"http:\/\/www.pamina-business.com\/wp-content\/uploads\/2016\/04\/passerelle.jpg","contentUrl":"http:\/\/www.pamina-business.com\/wp-content\/uploads\/2016\/04\/passerelle.jpg"},{"@type":"BreadcrumbList","@id":"http:\/\/www.pamina-business.com\/de\/de-nouvelles-passerelles-entre-rhin-et-lauter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.pamina-business.com\/de\/"},{"@type":"ListItem","position":2,"name":"De nouvelles passerelles entre Rhin et Lauter"}]},{"@type":"WebSite","@id":"https:\/\/www.pamina-business.com\/#website","url":"https:\/\/www.pamina-business.com\/","name":"PAMINA Business Club","description":"Un site utilisant WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pamina-business.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.pamina-business.com\/#\/schema\/person\/9ab02536dbdbc5e3ef40bbc3452c8c69","name":"Monique STUTZMANN","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/cc1c3adf9a9f6e969d3da7b6b34ec66f5f4a6844dfc9145380a75e42cd91882e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cc1c3adf9a9f6e969d3da7b6b34ec66f5f4a6844dfc9145380a75e42cd91882e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cc1c3adf9a9f6e969d3da7b6b34ec66f5f4a6844dfc9145380a75e42cd91882e?s=96&d=mm&r=g","caption":"Monique STUTZMANN"},"url":"http:\/\/www.pamina-business.com\/de\/author\/monique\/"}]}},"_links":{"self":[{"href":"http:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/posts\/1520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/comments?post=1520"}],"version-history":[{"count":2,"href":"http:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/posts\/1520\/revisions"}],"predecessor-version":[{"id":1523,"href":"http:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/posts\/1520\/revisions\/1523"}],"wp:attachment":[{"href":"http:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/media?parent=1520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/categories?post=1520"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.pamina-business.com\/de\/wp-json\/wp\/v2\/tags?post=1520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}